{"id":47785,"date":"2023-11-16T12:41:44","date_gmt":"2023-11-16T15:41:44","guid":{"rendered":"https:\/\/www.policiadelneuquen.gob.ar\/?p=47785"},"modified":"2023-11-16T12:43:26","modified_gmt":"2023-11-16T15:43:26","slug":"neuquen-demorado-por-robo-infraganti-con-dos-pedidos-de-captura-vigente","status":"publish","type":"post","link":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/neuquen-demorado-por-robo-infraganti-con-dos-pedidos-de-captura-vigente\/","title":{"rendered":"Neuqu\u00e9n: Demorado por robo infraganti con dos pedidos de captura vigentes"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"47785\" class=\"elementor elementor-47785\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c3c2197 e-flex e-con-boxed e-con e-parent\" data-id=\"7c3c2197\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a55838a elementor-widget elementor-widget-text-editor\" data-id=\"3a55838a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<h3>En la madrugada del jueves (16\/11) personal de Comisar\u00eda 1\u00b0 y Comisaria 2\u00b0, demoraron a un sujeto por presunto robo infraganti, el mismo contaba con dos pedidos de captura vigente.\u00a0<\/h3>\n<h3><\/h3>\n<h3>Pasadas las 01:30 Hs , a ra\u00edz de un llamado telef\u00f3nico, y el trabajo en conjunto de las Dependencias Policiales antes mencionadas, se logr\u00f3 demorar a un sujeto mientras forcejeaba las persianas de un local comercial en calles Sarmiento y Leguizam\u00f3n de la ciudad capital.\u00a0<\/h3>\n<h3><\/h3>\n<h3>Luego de su correcta identificaci\u00f3n y demora, se constat\u00f3 que recaian dos pedidos de captura vigentes sobre el mismo.\u00a0<\/h3>\n<h3><\/h3>\n<h3>Finalmente se trasladaron al demorado a sede Policial, quedando este a\u00a0 disposici\u00f3n de la Justicia interviniente<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En la madrugada del jueves (16\/11) personal de Comisar\u00eda 1\u00b0 y Comisaria 2\u00b0, demoraron a un sujeto por presunto robo infraganti, el mismo contaba con dos pedidos de captura vigente.\u00a0 Pasadas las 01:30 Hs , a ra\u00edz de un llamado telef\u00f3nico, y el trabajo en conjunto de las Dependencias Policiales antes mencionadas, se logr\u00f3 demorar [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":47786,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-47785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"jetpack_featured_media_url":"https:\/\/www.policiadelneuquen.gob.ar\/wp-content\/uploads\/2023\/11\/161107.jpg","_links":{"self":[{"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/47785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=47785"}],"version-history":[{"count":5,"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/47785\/revisions"}],"predecessor-version":[{"id":47792,"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/47785\/revisions\/47792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/47786"}],"wp:attachment":[{"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=47785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=47785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=47785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}