{"id":55290,"date":"2024-04-23T10:21:11","date_gmt":"2024-04-23T13:21:11","guid":{"rendered":"https:\/\/www.policiadelneuquen.gob.ar\/?p=55290"},"modified":"2024-04-23T10:21:15","modified_gmt":"2024-04-23T13:21:15","slug":"san-martin-de-los-andes-allanamientos-por-robo","status":"publish","type":"post","link":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/san-martin-de-los-andes-allanamientos-por-robo\/","title":{"rendered":"SAN MART\u00cdN DE LOS ANDES: Allanamientos por robo"},"content":{"rendered":"\n<p>El lunes 22 en horas personal de la Divisi\u00f3n Brigada de Investigaciones, con la colaboraci\u00f3n de efectivos de Comisar\u00eda 43\u00b0 llevaron a cabo diligencias de allanamiento en dos domicilios en la localidad de San Mart\u00edn de los Andes, los que arrojaron resultados positivos para la investigaci\u00f3n en curso.<\/p>\n\n\n\n<p>El personal policial logr\u00f3 el secuestro de elementos de construcci\u00f3n, herramientas el\u00e9ctricas, y el veh\u00edculo que fuera utilizado por los presuntos autores, para facilitar el transporte de los elementos sustra\u00eddos, procediendo, adem\u00e1s, a la aprehensi\u00f3n de dos hombres de 32 y 20 a\u00f1os.<\/p>\n\n\n\n<p>Las \u00f3rdenes de allanamientos fueron dispuestas por el juzgado de garant\u00edas a instancia de la fiscal\u00eda con asientos en la localidad cordillerana y fueron el corolario de una investigaci\u00f3n con tareas de campo llevadas a cabo por el personal de la unidad especial, a ra\u00edz de la denuncia de un hecho delictivo, ocurrido en un domicilio de la mencionada localidad, d\u00edas atr\u00e1s.<\/p>\n\n\n\n<p>Los elementos secuestrados y los ciudadanos aprehendidos fueron puestos a disposici\u00f3n de la fiscal\u00eda. De la investigaci\u00f3n y diligencias colaboraron activamente, personal de la Comisar\u00eda 43\u00b0, Divisi\u00f3n Operativa del Comando Radioel\u00e9ctrico y Divisi\u00f3n Tr\u00e1nsito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El lunes 22 en horas personal de la Divisi\u00f3n Brigada de Investigaciones, con la colaboraci\u00f3n de efectivos de Comisar\u00eda 43\u00b0 llevaron a cabo diligencias de allanamiento en dos domicilios en la localidad de San Mart\u00edn de los Andes, los que arrojaron resultados positivos para la investigaci\u00f3n en curso. El personal policial logr\u00f3 el secuestro de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":55291,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-55290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"jetpack_featured_media_url":"https:\/\/www.policiadelneuquen.gob.ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-23-at-9.06.22-AM.jpeg","_links":{"self":[{"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/55290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=55290"}],"version-history":[{"count":2,"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/55290\/revisions"}],"predecessor-version":[{"id":55296,"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/55290\/revisions\/55296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/55291"}],"wp:attachment":[{"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=55290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=55290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.policiadelneuquen.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=55290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}